{"id":3,"date":"2023-10-04T15:31:30","date_gmt":"2023-10-04T15:31:30","guid":{"rendered":"https:\/\/oller.cl\/?page_id=3"},"modified":"2023-12-28T21:31:46","modified_gmt":"2023-12-28T21:31:46","slug":"terminos-y-condiciones","status":"publish","type":"page","link":"https:\/\/oller.cl\/es\/terminos-y-condiciones\/","title":{"rendered":"T\u00e9rminos y Condiciones"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3\" class=\"elementor elementor-3\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56e4593 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"56e4593\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5e9ed679\" data-id=\"5e9ed679\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5111e7dc elementor-widget elementor-widget-text-editor\" data-id=\"5111e7dc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<!-- wp:list {\"ordered\":true} -->\n<ul><!-- wp:list-item -->\n<li>El presente Aviso Legal (en adelante, el \u201cAviso Legal\u201d) establece los T\u00e9rminos y Condiciones respecto al uso de las p\u00e1ginas de Internet, (las \u201cP\u00e1ginas) que Oller y C\u00eda Ltda. (\u201cLa Empresa\u201d,\u00a0pone a disposici\u00f3n de usted.<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>La sociedad que administra las P\u00e1ginas es: <strong>Oller &amp; C\u00eda. Ltda. 88.041.000-8<\/strong><\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>Las publicaciones digitales de\u00a0La Empresa tienen por objeto facilitar a sus Clientes y al p\u00fablico en general, el acceso a los productos La Empresa, as\u00ed como a la informaci\u00f3n relativa a dichos productos, equipos, promociones, y cualquier otra informaci\u00f3n relacionada (En adelante los \u201cServicios y Productos\u201d).<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>La utilizaci\u00f3n de las p\u00e1ginas le atribuye a Ud. la condici\u00f3n de usuario de las P\u00e1ginas (en adelante, el \u201cUsuario\u201d) e implica la aceptaci\u00f3n plena y sin reservas de todas y cada una de las disposiciones incluidas en este Aviso Legal en la versi\u00f3n publicada por La Empresa\u00a0en el momento mismo en que el usuario acceda a las p\u00e1ginas. En consecuencia, el usuario debe leer el presente Aviso Legal en cada una de las ocasiones en que utilice las p\u00e1ginas, ya que puede sufrir modificaciones.<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>La utilizaci\u00f3n de las p\u00e1ginas se encuentra sometida, adem\u00e1s de este Aviso Legal, a todos los avisos, reglamentos de uso e instrucciones, que sean puestos en conocimiento del Usuario por La Empresa\u00a0a trav\u00e9s de las p\u00e1ginas.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list --><!-- wp:paragraph -->\n<p>El uso de ciertos Servicios y Productos ofrecidos a los Usuarios a trav\u00e9s de las p\u00e1ginas puede estar sometido a condiciones particulares espec\u00edficas (en adelante, las \u201cCondiciones Particulares\u201d) que, seg\u00fan sea el caso, pueden sustituir, completar y\/o modificar el presente Aviso Legal. Por lo tanto, previa a la utilizaci\u00f3n de dichos Servicios y Productos, el Usuario deber\u00e1 leer las correspondientes Condiciones Particulares de que se trate. Otros Servicios y Productos contenidos en las p\u00e1ginas pueden encontrarse sujetos a la firma por escrito de un contrato de servicios (en adelante el \u201cContrato de Servicios\u201d) por parte del Usuario, as\u00ed como a la aprobaci\u00f3n correspondiente por parte de La Empresa.<\/p>\n<!-- \/wp:paragraph --><!-- wp:list {\"ordered\":true} -->\n<ul><!-- wp:list-item -->\n<li>La Empresa\u00a0se reserva el derecho a modificar el Aviso Legal en cualquier tiempo y sin previa notificaci\u00f3n. Dichas modificaciones ser\u00e1n efectivas a partir del momento en que queden disponibles al p\u00fablico en las p\u00e1ginas. El usuario se considera enterado y obligado por los cambios al Aviso Legal desde el momento en que ingrese a las p\u00e1ginas. El uso o acceso a las p\u00e1ginas por parte del usuario constituir\u00e1 la aceptaci\u00f3n y acuerdo a los cambios del Aviso Legal.<br \/>De igual manera, La Empresa\u00a0se reserva la facultad de efectuar, en cualquier momento, modificaciones en la informaci\u00f3n contenida en sus publicaciones digitales.<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>La Empresa\u00a0procurar\u00e1 que la informaci\u00f3n contenida en sus p\u00e1ginas sea correcta y est\u00e9 actualizada al momento de ser incluida en las mismas. Sin embargo, es posible que existan errores o imprecisiones involuntarias.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list --><!-- wp:paragraph -->\n<p>La Empresa no se responsabilizar\u00e1 por errores u omisiones contenidas en sus p\u00e1ginas, ni se compromete a la actualizaci\u00f3n inmediata de la informaci\u00f3n contenida en sus publicaciones digitales.<\/p>\n<!-- \/wp:paragraph --><!-- wp:list {\"ordered\":true} -->\n<ul><!-- wp:list-item -->\n<li>La Empresa\u00a0podr\u00e1 en cualquier momento negar, suspender o dar por terminado el acceso o el uso del usuario a las p\u00e1ginas, a cualquier Servicio y Producto, o cualquier parte de los mismos, a sola discreci\u00f3n de La Empresa, sin necesidad de previo aviso, sin limitaci\u00f3n alguna, y por cualquier raz\u00f3n.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list --><!-- wp:paragraph -->\n<p>Por lo anterior, La Empresa\u00a0no garantiza la utilidad, disponibilidad y continuidad del funcionamiento de las p\u00e1ginas as\u00ed como de los Servicios y Productos para la realizaci\u00f3n de alguna actividad en espec\u00edfico, o su infalibilidad.<\/p>\n<!-- \/wp:paragraph --><!-- wp:list {\"ordered\":true} -->\n<ul><!-- wp:list-item -->\n<li>La Empresa\u00a0es titular de todos los derechos sobre el software de las publicaciones digitales, as\u00ed como de los derechos de propiedad industrial e intelectual referidos a los contenidos que en ellas se incluyan, a excepci\u00f3n de los derechos sobre productos y servicios que no son propiedad de La Empresa, cuyas marcas est\u00e1n registradas a favor de sus respectivos titulares, y como tal son reconocidas por La Empresa. Ning\u00fan material de las publicaciones digitales podr\u00e1 ser reproducido, copiado modificado, distribuido, transmitido, vendido, utilizado o publicado por el usuario sin el previo consentimiento por escrito de La Empresa.<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>Todas las marcas de terceros registradas por sus respectivos propietarios que aparecieran en las p\u00e1ginas ser\u00e1n solo a efectos de publicidad y de recopilaci\u00f3n de informaci\u00f3n. Sus propietarios pueden solicitar la modificaci\u00f3n o eliminaci\u00f3n de la informaci\u00f3n que les concierna. Por otro lado, la aparici\u00f3n de estas terceras marcas no implica necesariamente la recomendaci\u00f3n de las mismas.<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>La Empresa\u00a0respetar\u00e1 escrupulosamente la confidencialidad de los datos de car\u00e1cter personal aportados por los visitantes a las publicaciones digitales, mediante la observancia de la normativa aplicable vigente, de tal manera que La Empresa\u00a0no entregar\u00e1 informaci\u00f3n personal del usuario a terceros, a menos que sea requerido para entregar un producto o prestar un servicio solicitado por el usuario.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list --><!-- wp:paragraph -->\n<p>No obstante lo se\u00f1alado anteriormente, y dada la naturaleza de Internet, La Empresa\u00a0no garantiza que todo uso de las P\u00e1ginas o Servicios y Productos proporcionados a trav\u00e9s de las mismas se encuentre libre de riesgo, por lo que La Empresa\u00a0no tendr\u00e1 responsabilidad alguna, incluyendo los da\u00f1os, perjuicios o cualquier otra que pudiera ser ocasionada por el mal uso de terceros de la informaci\u00f3n generada, recibida, transmitida, o archivada en las p\u00e1ginas.<\/p>\n<!-- \/wp:paragraph --><!-- wp:list {\"ordered\":true} -->\n<ul><!-- wp:list-item -->\n<li>Cualquier informaci\u00f3n enviada por los usuarios y que sea recibida en las p\u00e1ginas, tal como comentarios, sugerencias o ideas, se considerar\u00e1 cedida a La Empresa\u00a0a t\u00edtulo gratuito, y el usuario que la env\u00ede acepta impl\u00edcitamente que no tiene car\u00e1cter de confidencial. Le sugerimos que NO ENV\u00cdE informaci\u00f3n que no pueda ser tratada de esta forma. La Empresa\u00a0tendr\u00e1 el derecho de utilizar cualquier informaci\u00f3n enviada para los fines que juzgue convenientes.<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>Queda terminantemente prohibido el mal uso y el uso no autorizado de las p\u00e1ginas, incluyendo sin limitar, el acceso no autorizado a los sistemas de La Empresa, el mal uso de claves o contrase\u00f1as (\u201cPasswords\u201d), o de cualquier informaci\u00f3n contenida en las P\u00e1ginas. La Empresa\u00a0se reserva el derecho de suspender o negar el acceso a sus p\u00e1ginas a las personas que hagan un mal uso de la informaci\u00f3n o de los Servicios y Productos contenidos en las mismas; sin perjuicio del derecho de La Empresa\u00a0del ejercicio de las acciones civiles, administrativas o penales a que hubiere lugar, de conformidad con las leyes de la materia.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<p>El Usuario acepta sacar en paz y a salvo a La Empresa, as\u00ed como indemnizarle por cualquier responsabilidad, costo o gasto que se le impute por el uso por parte del usuario de las p\u00e1ginas o los Servicios y Productos para cualquier fin prohibido o ilegal, o la violaci\u00f3n de las reglas de estas P\u00e1ginas, cualquier Contrato de Servicios, cualquier derecho de terceros, incluyendo de manera enunciativa, mas no limitativa, los derechos de autor, de propiedad industrial, o de cualquier ley, reglamento o c\u00f3digo federal, estatal o municipal aplicable. Dichas obligaciones continuar\u00e1n a\u00fan despu\u00e9s de la terminaci\u00f3n de este Aviso Legal, Condiciones Particulares o Contrato de Servicios.<\/p>\n<ul>\n<li>La Empresa\u00a0excluye cualquier responsabilidad civil, penal, administrativa, o por los da\u00f1os y perjuicios directos o indirectos, o cualquier otro causado o derivado de:<!-- wp:list {\"ordered\":true} -->\n<ul><!-- wp:list-item -->\n<li>La presencia de virus u otros elementos lesivos en los Servicios y Productos prestados a trav\u00e9s de las p\u00e1ginas de La Empresa\u00a0o por terceros que tengan un Link con las P\u00e1ginas que puedan producir alteraciones en el sistema inform\u00e1tico o documentos electr\u00f3nicos de los usuarios.<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>Errores u omisiones contenidas en las p\u00e1ginas, o uso de la informaci\u00f3n contenida en las mismas. Cualquier decisi\u00f3n basada en la informaci\u00f3n contenida en estas p\u00e1ginas ser\u00e1 responsabilidad del visitante.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<!-- \/wp:list --><!-- wp:paragraph -->\n<p>\u00a0<\/p>\n<!-- \/wp:paragraph -->\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-abbd446\" data-id=\"abbd446\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bec33c elementor-widget elementor-widget-text-editor\" data-id=\"2bec33c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n<ul><!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>El uso o imposibilidad de uso de las p\u00e1ginas, Servicios y Productos o cualquiera de sus partes, o de sus links, incluyendo cualquier p\u00e9rdida de programas o informaci\u00f3n.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>El uso y la informaci\u00f3n disponible en cualquier link a las p\u00e1ginas de La Empresa.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>El conocimiento que puedan tener terceros no autorizados de la clase, condiciones, caracter\u00edsticas y circunstancias del uso que los Usuarios hacen de las p\u00e1ginas y de los Servicios y Productos.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>El acceso a las p\u00e1ginas o el uso de informaci\u00f3n o aplicaciones en ella contenidas que generen da\u00f1os en el software o hardware del usuario.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>El mal uso de terceros de la informaci\u00f3n generada, recibida, transmitida, o archivada en las p\u00e1ginas.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list --><\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Formas de pago, despacho, y derechos del Usuario<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ul><!-- wp:list-item -->\n<li>Las compras online, se pueden realizar las 24 horas del d\u00eda, se cierra el d\u00eda a las __.00 horas del d\u00eda h\u00e1bil correspondiente a la compra, despu\u00e9s de esa hora pasa inmediatamente al d\u00eda siguiente.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Formas de pago aceptadas:<!-- wp:list {\"ordered\":true} -->\n<ul><!-- wp:list-item -->\n<li>Transferencia \/ Dep\u00f3sito: Debe transferir o depositar el total exacto de su pedido a: Nombre del titular: <strong>Oller &amp; C\u00eda. Ltda. <\/strong>Banco: Santander, Rut: 88.041.000-8, Cuenta corriente: 2569858-4, Mail: contabilidad@oller.cl<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list --><\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Para generar el despacho de los productos debe enviar el comprobante de dep\u00f3sito por e-mail a cotizaci\u00f3n@oller.cl. La orden de compra se cursar\u00e1 una vez confirmado y liberado los fondos en nuestra cuenta bancaria.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ul><!-- wp:list-item -->\n<li>Tarjetas de Cr\u00e9dito: Se aceptan las tarjetas de cr\u00e9dito Visa, MasterCard, Diners Club, American Express y Magna a trav\u00e9s del sistema de pago Web Pay Plus. Los datos de la tarjeta son procesados directamente por Transbank S.A. a trav\u00e9s del sistema Web Pay Plus. La orden de compra y posterior despacho se cursar\u00e1 despu\u00e9s de haber recibido la aprobaci\u00f3n del pago.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>FACTURAS: el cliente debe indicar al momento de la compra que desea factura y todos los datos de esta.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ul><!-- wp:list-item -->\n<li>La Empresa se reserva el derecho de reversar una compra a trav\u00e9s del sistema webpay, si no es posible hacer entrega de la mercader\u00eda en forma personalizada al emisor de la tarjeta, o bien no es posible contactar al Usuario para confirmar su transacci\u00f3n<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Todo despacho se realizar\u00e1 en\u00a0 __5__ d\u00edas h\u00e1biles dentro de la regi\u00f3n metropolitana, una vez que se encuentre acreditado el pago, ya sea mediante dep\u00f3sito con documento o tarjeta de cr\u00e9dito.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>La Empresa contrata a petici\u00f3n del Usuario un servicio de transporte de acuerdo a lo siguiente:<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Despacho a domicilio: Usuario paga despacho a trav\u00e9s de (p\u00e1gina web) y producto es entregado directamente en su casa por empresa de transporte utilizada por La Empresa<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ul><!-- wp:list-item -->\n<li>El compromiso de La Empresa es entregar el pedido a la empresa que transportar\u00e1 el producto entre 2 y 3 d\u00edas h\u00e1biles. Luego de eso, los tiempos de entrega de las empresas de transporte se rigen de acuerdo a sus propias pol\u00edticas y no son bajo ninguna circunstancia responsabilidad de La Empresa.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>El titular de la tarjeta de cr\u00e9dito debe ser el mismo del C.I. (RUT) del comprador registrado, La Empresa puede solicitar confirmaci\u00f3n de esta informaci\u00f3n.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>La Empresa se reserva el derecho de anular la compra en caso que la informaci\u00f3n enviada por el Usuario sea inconsistente en relaci\u00f3n a las exigencias de acreditaci\u00f3n requeridas por las instituciones financieras relacionadas. El stock mostrado en la p\u00e1gina web puede tener un desfase con el stock real, por tanto, toda compra queda sujeta a disponibilidad de stock. En caso que se realice una compra y el producto est\u00e9 agotado, La Empresa gestionar\u00e1 la reversa de la compra para hacer devoluci\u00f3n del monto.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>El Usuario podr\u00e1 comprar todos los productos disponibles en el cat\u00e1logo. En Chile no hay restricciones de cantidad. Para el extranjero se rige por las pol\u00edticas propias de cada pa\u00eds y los acuerdos comerciales vigentes entre los respectivos pa\u00edses, en relaci\u00f3n a las mercader\u00edas adquiridas.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Los pedidos son enviados a la direcci\u00f3n que indique el Usuario en su compra y con cargo a \u00e9l mismo. El Usuario acepta que reciba todo morador o recepcionista de esta direcci\u00f3n, o bien debe indicar expresamente el nombre de contacto para la recepci\u00f3n de la compra. Si en primer despacho no hay quien reciba el producto despachado, el Usuario deber\u00e1 asumir el costo de un nuevo despacho, La Empresa no se hace cargo de la no recepci\u00f3n del despacho.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Cada producto est\u00e1 debidamente singularizado con su peso respectivo para as\u00ed definir los costos de traslado lo m\u00e1s exacto posible, logrando as\u00ed minimizar los valores de despacho de cada pedido.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>La mercader\u00eda se enviar\u00e1 con una orden emitida por la empresa de transporte, la cual se debe firmar como aceptaci\u00f3n de la correcta orden de compra. El Usuario o quien reciba las mercader\u00edas en su nombre debe revisar que los productos detallados correspondan a lo solicitado, y que tanto el embalaje como su contenido se encuentren en buen estado.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Si el embalaje se encuentra en mal estado, el Usuario o quien reciba las mercader\u00edas en su nombre, debe hacer el reclamo inmediatamente a la empresa de transporte.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>En caso que el producto se encuentre defectuoso, el Usuario o quien reciba las mercader\u00edas en su nombre, debe notificar v\u00eda e-mail dentro de las 24 horas siguientes a la entrega, a <strong>(<\/strong><strong>jvalencia@oller.cl)<\/strong> para hacer uso de la garant\u00eda del productor. Todo cambio debe ser presentando boleta o factura de venta.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Toda compra conlleva una boleta, copia de la cual se adjuntar\u00e1 al despacho.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Para generar el despacho de los productos debe enviar el comprobante de dep\u00f3sito por e-mail a jvalencia@oller.cl<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>La orden de compra se cursar\u00e1 una vez confirmado y liberado los fondos en nuestra cuenta bancaria.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>No se aceptan devoluciones o el derecho a retracto unilateral establecido en el art\u00edculo 3\u00b0 bis de la Ley de Protecci\u00f3n al Consumidor, una vez recibido el pedido f\u00edsicamente y recepcionado conforme por el Usuario o quien reciba las mercader\u00edas en su nombre. Le sugerimos revisarlo muy bien al momento de recibir su carga y rechazarlo si presenta alteraciones<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Podr\u00e1 anular un pedido en cualquier momento o reemplazarlo por otro, antes que sea despachado. La Empresa podr\u00e1 anular una venta en caso que el precio y\/o stock no se encuentre actualizado de acuerdo a sus registros internos.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Realizaremos cambios solo con la boleta o factura de compra, es responsabilidad del Usuario guardar el documento que corresponda para efectuar el cambio, de acuerdo a lo establecido en la Ley de Protecci\u00f3n al Consumidor.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>El producto debe estar SIN USO alguno (de lo contrario no proceder\u00e1 el cambio) Cambio por producto nuevo 30 d\u00edas desde que se realiz\u00f3 la compra (Afecto a stock disponible).<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Si el Usuario solicita cambio de producto, es el Usuario quien asume el costo de despacho del producto hac\u00eda las bodegas de La Empresa y tambi\u00e9n el costo del despacho del nuevo producto hac\u00eda la direcci\u00f3n solicitada.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ul><!-- wp:list-item -->\n<li>El Usuario tiene, dentro de los 90 d\u00edas siguientes a la recepci\u00f3n del producto, el denominado \u201cderecho de opci\u00f3n\u201d, como garant\u00eda de sus derechos, que consiste en:<!-- wp:list {\"ordered\":true} -->\n<ul><!-- wp:list-item -->\n<li>Reparaci\u00f3n gratuita del bien;<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Previa restituci\u00f3n, la reposici\u00f3n; o<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>La devoluci\u00f3n de la cantidad pagada.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list --><\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Estos derechos solo ser\u00e1n aplicables a fallas de fabricaci\u00f3n, en ning\u00fan caso estas cubrir\u00e1n el mal uso del producto por parte del Usuario.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Para el ejercicio de este derecho, el Usuario debe necesariamente contar con la boleta o factura.<\/p>\n<!-- \/wp:paragraph -->\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>El uso de ciertos Servicios y Productos ofrecidos a los Usuarios a trav\u00e9s de las p\u00e1ginas puede estar sometido a condiciones particulares espec\u00edficas (en adelante, las \u201cCondiciones Particulares\u201d) que, seg\u00fan sea el caso, pueden sustituir, completar y\/o modificar el presente Aviso Legal. Por lo tanto, previa a la utilizaci\u00f3n de dichos Servicios y Productos, el [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>T\u00e9rminos y Condiciones - Oller<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oller.cl\/es\/terminos-y-condiciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00e9rminos y Condiciones - Oller\" \/>\n<meta property=\"og:description\" content=\"El uso de ciertos Servicios y Productos ofrecidos a los Usuarios a trav\u00e9s de las p\u00e1ginas puede estar sometido a condiciones particulares espec\u00edficas (en adelante, las \u201cCondiciones Particulares\u201d) que, seg\u00fan sea el caso, pueden sustituir, completar y\/o modificar el presente Aviso Legal. Por lo tanto, previa a la utilizaci\u00f3n de dichos Servicios y Productos, el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oller.cl\/es\/terminos-y-condiciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Oller\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-28T21:31:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/oller.cl\/terminos-y-condiciones\/\",\"url\":\"https:\/\/oller.cl\/terminos-y-condiciones\/\",\"name\":\"T\u00e9rminos y Condiciones - Oller\",\"isPartOf\":{\"@id\":\"https:\/\/oller.cl\/#website\"},\"datePublished\":\"2023-10-04T15:31:30+00:00\",\"dateModified\":\"2023-12-28T21:31:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/oller.cl\/terminos-y-condiciones\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/oller.cl\/terminos-y-condiciones\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/oller.cl\/terminos-y-condiciones\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/oller.cl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e9rminos y Condiciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/oller.cl\/#website\",\"url\":\"https:\/\/oller.cl\/\",\"name\":\"Oller\",\"description\":\"Equipamiento M\u00e9dico e Instrumental Quir\u00fargico\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/oller.cl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e9rminos y Condiciones - Oller","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oller.cl\/es\/terminos-y-condiciones\/","og_locale":"es_ES","og_type":"article","og_title":"T\u00e9rminos y Condiciones - Oller","og_description":"El uso de ciertos Servicios y Productos ofrecidos a los Usuarios a trav\u00e9s de las p\u00e1ginas puede estar sometido a condiciones particulares espec\u00edficas (en adelante, las \u201cCondiciones Particulares\u201d) que, seg\u00fan sea el caso, pueden sustituir, completar y\/o modificar el presente Aviso Legal. Por lo tanto, previa a la utilizaci\u00f3n de dichos Servicios y Productos, el [&hellip;]","og_url":"https:\/\/oller.cl\/es\/terminos-y-condiciones\/","og_site_name":"Oller","article_modified_time":"2023-12-28T21:31:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/oller.cl\/terminos-y-condiciones\/","url":"https:\/\/oller.cl\/terminos-y-condiciones\/","name":"T\u00e9rminos y Condiciones - Oller","isPartOf":{"@id":"https:\/\/oller.cl\/#website"},"datePublished":"2023-10-04T15:31:30+00:00","dateModified":"2023-12-28T21:31:46+00:00","breadcrumb":{"@id":"https:\/\/oller.cl\/terminos-y-condiciones\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oller.cl\/terminos-y-condiciones\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/oller.cl\/terminos-y-condiciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/oller.cl\/"},{"@type":"ListItem","position":2,"name":"T\u00e9rminos y Condiciones"}]},{"@type":"WebSite","@id":"https:\/\/oller.cl\/#website","url":"https:\/\/oller.cl\/","name":"Oller","description":"Equipamiento M\u00e9dico e Instrumental Quir\u00fargico","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oller.cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"}]}},"_links":{"self":[{"href":"https:\/\/oller.cl\/es\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oller.cl\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oller.cl\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oller.cl\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oller.cl\/es\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":0,"href":"https:\/\/oller.cl\/es\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"wp:attachment":[{"href":"https:\/\/oller.cl\/es\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}